{"id":15013,"date":"2021-12-21T13:27:55","date_gmt":"2021-12-21T11:27:55","guid":{"rendered":"https:\/\/md-magazine.info\/md-issue\/04-2021\/"},"modified":"2025-09-02T16:16:21","modified_gmt":"2025-09-02T13:16:21","slug":"04-2021","status":"publish","type":"post","link":"https:\/\/md-magazine.info\/en\/md-issue\/04-2021\/","title":{"rendered":"04\/2021"},"content":{"rendered":"<div class=\"real3dflipbook\" id=\"56_6a5787adc817a\" style=\"position:absolute;\"><\/div><script type=\"application\/json\" class=\"real3dflipbook-options\" data-book-id=\"56_6a5787adc817a\">{\"name\":\"04\/2021\",\"pdfUrl\":\"https:\/\/md-magazine.info\/app\/uploads\/2021\/12\/MD_2021_04_Jpg_LowRes.pdf\",\"bookId\":\"56\",\"id\":\"56\",\"date\":\"2021-12-21 13:23:08\",\"status\":\"published\",\"pages\":[],\"tableOfContent\":[],\"post_id\":23921,\"securePdf\":false,\"rootFolder\":\"https:\/\/md-magazine.info\/app\/plugins\/real3d-flipbook\/\",\"version\":\"4.20\",\"uniqueId\":\"56_6a5787adc817a\",\"previewPages\":\"0\",\"notes\":[],\"s\":\"12345678\"}<\/script><script type=\"application\/json\" id=\"real3dflipbook-global-options\">{\"pages\":[],\"pdfUrl\":\"\",\"printPdfUrl\":\"\",\"tableOfContent\":[],\"id\":\"\",\"bookId\":\"\",\"date\":\"\",\"lightboxThumbnailUrl\":\"\",\"mode\":\"normal\",\"viewMode\":\"simple\",\"pageTextureSize\":\"2048\",\"pageTextureSizeSmall\":\"1500\",\"pageTextureSizeMobile\":\"1280\",\"pageTextureSizeMobileSmall\":\"1024\",\"rangeChunkSize\":\"256\",\"minPixelRatio\":\"1\",\"pdfTextLayer\":\"true\",\"zoomMin\":\"0.9\",\"zoomStep\":\"2\",\"zoomSize\":\"\",\"zoomReset\":\"false\",\"doubleClickZoom\":\"true\",\"pageDrag\":\"true\",\"singlePageMode\":\"false\",\"pageFlipDuration\":\"1\",\"sound\":\"false\",\"startPage\":\"1\",\"pageNumberOffset\":\"0\",\"deeplinking\":{\"enabled\":\"false\",\"prefix\":\"\"},\"responsiveView\":\"false\",\"responsiveViewTreshold\":\"768\",\"responsiveViewRatio\":\"1\",\"minimalView\":\"true\",\"minimalViewBreakpoint\":\"600\",\"cover\":\"true\",\"backCover\":\"false\",\"scaleCover\":\"false\",\"pageCaptions\":\"false\",\"height\":\"400\",\"responsiveHeight\":\"true\",\"containerRatio\":\"\",\"thumbnailsOnStart\":\"false\",\"contentOnStart\":\"false\",\"searchOnStart\":\"\",\"searchResultsThumbs\":\"false\",\"tableOfContentCloseOnClick\":\"true\",\"thumbsCloseOnClick\":\"true\",\"autoplayOnStart\":\"false\",\"autoplayInterval\":\"3000\",\"autoplayLoop\":\"true\",\"autoplayStartPage\":\"1\",\"rightToLeft\":\"false\",\"pageWidth\":\"\",\"pageHeight\":\"\",\"thumbSize\":\"130\",\"logoImg\":\"\",\"logoUrl\":\"\",\"logoUrlTarget\":\"_blank\",\"logoCSS\":\"position:absolute;left:0;top:0;\",\"menuSelector\":\"\",\"zIndex\":\"auto\",\"preloaderText\":\"\u0417\u0430\u0440\u0435\u0436\u0434\u0430\u043d\u0435 \u043d\u0430 \u0441\u043f\u0438\u0441\u0430\u043d\u0438\u0435\u0442\u043e\",\"googleAnalyticsTrackingCode\":\"\",\"pdfBrowserViewerIfIE\":\"false\",\"modeMobile\":\"normal\",\"viewModeMobile\":\"\",\"aspectMobile\":\"\",\"aspectRatioMobile\":\"0.71\",\"singlePageModeIfMobile\":\"false\",\"logoHideOnMobile\":\"false\",\"mobile\":{\"thumbnailsOnStart\":\"false\",\"contentOnStart\":\"false\",\"pagesInMemory\":\"6\",\"bitmapResizeHeight\":\"\",\"bitmapResizeQuality\":\"\",\"currentPage\":{\"enabled\":\"false\"},\"pdfUrl\":\"\",\"minimalViewBreakpoint\":\"360\"},\"lightboxCssClass\":\"\",\"lightboxLink\":\"\",\"lightboxLinkNewWindow\":\"true\",\"lightboxBackground\":\"rgb(81, 85, 88)\",\"lightboxBackgroundPattern\":\"\",\"lightboxBackgroundImage\":\"\",\"lightboxContainerCSS\":\"display:inline-block;padding:10px;\",\"lightboxThumbnailHeight\":\"300\",\"lightboxThumbnailUrlCSS\":\"display:block;\",\"lightboxThumbnailInfo\":\"false\",\"lightboxThumbnailInfoText\":\"\",\"lightboxThumbnailInfoCSS\":\"top: 0;  width: 100%; height: 100%; font-size: 16px; color: #000; background: rgba(255,255,255,.8);\",\"showTitle\":\"false\",\"showDate\":\"false\",\"hideThumbnail\":\"false\",\"lightboxText\":\"\",\"lightboxTextCSS\":\"display:block;\",\"lightboxTextPosition\":\"top\",\"lightBoxOpened\":\"false\",\"lightBoxFullscreen\":\"false\",\"lightboxStartPage\":\"\",\"lightboxMarginV\":\"0\",\"lightboxMarginH\":\"0\",\"lights\":\"true\",\"lightPositionX\":\"0\",\"lightPositionY\":\"150\",\"lightPositionZ\":\"1400\",\"lightIntensity\":\"0.6\",\"shadows\":\"true\",\"shadowMapSize\":\"2048\",\"shadowOpacity\":\"0.2\",\"shadowDistance\":\"15\",\"pageHardness\":\"2\",\"coverHardness\":\"2\",\"pageRoughness\":\"1\",\"pageMetalness\":\"0\",\"pageSegmentsW\":\"6\",\"pageSegmentsH\":\"1\",\"pagesInMemory\":\"20\",\"bitmapResizeHeight\":\"\",\"bitmapResizeQuality\":\"\",\"pageMiddleShadowSize\":\"2\",\"pageMiddleShadowColorL\":\"#999999\",\"pageMiddleShadowColorR\":\"#777777\",\"antialias\":\"false\",\"pan\":\"0\",\"tilt\":\"0\",\"rotateCameraOnMouseDrag\":\"true\",\"panMax\":\"20\",\"panMin\":\"-20\",\"tiltMax\":\"0\",\"tiltMin\":\"-60\",\"currentPage\":{\"enabled\":\"true\",\"title\":\"Current page\",\"hAlign\":\"center\",\"vAlign\":\"top\"},\"btnAutoplay\":{\"enabled\":\"false\",\"title\":\"Autoplay\",\"vAlign\":\"top\",\"hAlign\":\"left\"},\"btnNext\":{\"enabled\":\"true\",\"title\":\"Next Page\"},\"btnLast\":{\"enabled\":\"false\",\"title\":\"Last Page\"},\"btnPrev\":{\"enabled\":\"true\",\"title\":\"Previous Page\"},\"btnFirst\":{\"enabled\":\"false\",\"title\":\"First Page\"},\"btnZoomIn\":{\"enabled\":\"false\",\"title\":\"Zoom in\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"btnZoomOut\":{\"enabled\":\"false\",\"title\":\"Zoom out\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"btnToc\":{\"enabled\":\"false\",\"title\":\"Table of Contents\",\"vAlign\":\"top\",\"hAlign\":\"left\"},\"btnThumbs\":{\"enabled\":\"false\",\"title\":\"Pages\",\"vAlign\":\"top\",\"hAlign\":\"left\"},\"btnShare\":{\"enabled\":\"false\",\"title\":\"Share\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"btnNotes\":{\"enabled\":\"false\",\"title\":\"Notes\"},\"btnDownloadPages\":{\"enabled\":\"false\",\"url\":\"\",\"title\":\"Download pages\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"btnDownloadPdf\":{\"enabled\":\"false\",\"url\":\"\",\"title\":\"Download PDF\",\"forceDownload\":\"true\",\"openInNewWindow\":\"true\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"btnSound\":{\"enabled\":\"false\",\"title\":\"Sound\",\"vAlign\":\"top\",\"hAlign\":\"left\"},\"btnExpand\":{\"enabled\":\"true\",\"title\":\"Toggle fullscreen\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"btnSingle\":{\"enabled\":\"true\",\"title\":\"Toggle single page\"},\"btnSearch\":{\"enabled\":\"false\",\"title\":\"Search\",\"vAlign\":\"top\",\"hAlign\":\"left\"},\"search\":{\"enabled\":\"false\",\"title\":\"Search\"},\"btnBookmark\":{\"enabled\":\"false\",\"title\":\"Bookmark\",\"vAlign\":\"top\",\"hAlign\":\"left\"},\"btnPrint\":{\"enabled\":\"false\",\"title\":\"Print\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"btnTools\":{\"enabled\":\"true\",\"title\":\"More\"},\"btnClose\":{\"enabled\":\"true\",\"title\":\"Close\"},\"whatsapp\":{\"enabled\":\"true\"},\"twitter\":{\"enabled\":\"true\"},\"facebook\":{\"enabled\":\"true\"},\"pinterest\":{\"enabled\":\"true\"},\"email\":{\"enabled\":\"true\"},\"linkedin\":{\"enabled\":\"true\"},\"digg\":{\"enabled\":\"false\"},\"reddit\":{\"enabled\":\"false\"},\"shareUrl\":\"\",\"shareTitle\":\"\",\"shareImage\":\"\",\"layout\":\"4\",\"icons\":\"FontAwesome\",\"skin\":\"light\",\"useFontAwesome5\":\"true\",\"sideNavigationButtons\":\"true\",\"menuNavigationButtons\":\"false\",\"backgroundColor\":\"rgb(81, 85, 88)\",\"backgroundPattern\":\"\",\"backgroundImage\":\"\",\"backgroundTransparent\":\"false\",\"menuBackground\":\"\",\"menuShadow\":\"\",\"menuMargin\":\"0\",\"menuPadding\":\"0\",\"menuOverBook\":\"false\",\"menuFloating\":\"false\",\"menuTransparent\":\"false\",\"menu2Background\":\"\",\"menu2Shadow\":\"\",\"menu2Margin\":\"0\",\"menu2Padding\":\"0\",\"menu2OverBook\":\"false\",\"menu2Floating\":\"false\",\"menu2Transparent\":\"false\",\"skinColor\":\"\",\"skinBackground\":\"\",\"hideMenu\":\"false\",\"menuAlignHorizontal\":\"center\",\"btnColor\":\"\",\"btnColorHover\":\"\",\"btnBackground\":\"none\",\"btnRadius\":\"0\",\"btnMargin\":\"2\",\"btnSize\":\"14\",\"btnPaddingV\":\"10\",\"btnPaddingH\":\"10\",\"btnShadow\":\"\",\"btnTextShadow\":\"\",\"btnBorder\":\"\",\"arrowColor\":\"#fff\",\"arrowColorHover\":\"#fff\",\"arrowBackground\":\"rgba(0,0,0,0)\",\"arrowBackgroundHover\":\"rgba(0, 0, 0, .15)\",\"arrowRadius\":\"4\",\"arrowMargin\":\"4\",\"arrowSize\":\"40\",\"arrowPadding\":\"10\",\"arrowTextShadow\":\"0px 0px 1px rgba(0, 0, 0, 1)\",\"arrowBorder\":\"\",\"closeBtnColorHover\":\"#FFF\",\"closeBtnBackground\":\"rgba(0,0,0,.4)\",\"closeBtnRadius\":\"0\",\"closeBtnMargin\":\"0\",\"closeBtnSize\":\"20\",\"closeBtnPadding\":\"5\",\"closeBtnTextShadow\":\"\",\"closeBtnBorder\":\"\",\"floatingBtnColor\":\"\",\"floatingBtnColorHover\":\"\",\"floatingBtnBackground\":\"\",\"floatingBtnBackgroundHover\":\"\",\"floatingBtnRadius\":\"\",\"floatingBtnMargin\":\"\",\"floatingBtnSize\":\"\",\"floatingBtnPadding\":\"\",\"floatingBtnShadow\":\"\",\"floatingBtnTextShadow\":\"\",\"floatingBtnBorder\":\"\",\"currentPageMarginV\":\"5\",\"currentPageMarginH\":\"5\",\"arrowsAlwaysEnabledForNavigation\":\"false\",\"arrowsDisabledNotFullscreen\":\"true\",\"touchSwipeEnabled\":\"true\",\"fitToWidth\":\"false\",\"rightClickEnabled\":\"false\",\"linkColor\":\"rgba(255,255,255,0)\",\"linkColorHover\":\"rgba(255,255,0,0)\",\"linkOpacity\":\"0.1\",\"linkTarget\":\"_blank\",\"pdfAutoLinks\":\"true\",\"disableRange\":\"false\",\"strings\":{\"print\":\"Print\",\"printLeftPage\":\"Print left page\",\"printRightPage\":\"Print right page\",\"printCurrentPage\":\"Print current page\",\"printAllPages\":\"Print all pages\",\"download\":\"Download\",\"downloadLeftPage\":\"Download left page\",\"downloadRightPage\":\"Download right page\",\"downloadCurrentPage\":\"Download current page\",\"downloadAllPages\":\"Download all pages\",\"bookmarks\":\"Bookmarks\",\"bookmarkLeftPage\":\"Bookmark left page\",\"bookmarkRightPage\":\"Bookmark right page\",\"bookmarkCurrentPage\":\"Bookmark current page\",\"search\":\"Search\",\"findInDocument\":\"Find in document\",\"pagesFoundContaining\":\"pages found containing\",\"noMatches\":\"No matches\",\"matchesFound\":\"matches found\",\"page\":\"Page\",\"matches\":\"matches\",\"thumbnails\":\"Thumbnails\",\"tableOfContent\":\"Table of Contents\",\"share\":\"Share\",\"pressEscToClose\":\"Press ESC to close\",\"password\":\"Password\",\"addNote\":\"Add note\",\"typeInYourNote\":\"Type in your note...\"},\"access\":\"full\",\"backgroundMusic\":\"\",\"cornerCurl\":\"false\",\"pdfTools\":{\"pageHeight\":1500,\"thumbHeight\":200,\"quality\":0.8000000000000000444089209850062616169452667236328125,\"textLayer\":\"true\",\"autoConvert\":\"true\"},\"slug\":\"\",\"convertPDFLinks\":\"true\",\"convertPDFLinksWithClass\":\"\",\"convertPDFLinksWithoutClass\":\"\",\"overridePDFEmbedder\":\"true\",\"overrideDflip\":\"true\",\"overrideWonderPDFEmbed\":\"true\",\"override3DFlipBook\":\"true\",\"overridePDFjsViewer\":\"true\",\"resumeReading\":\"false\",\"previewPages\":\"\",\"previewMode\":\"\",\"aspectRatio\":\"2\",\"pdfBrowserViewerIfMobile\":\"false\",\"pdfBrowserViewerFullscreen\":\"true\",\"pdfBrowserViewerFullscreenTarget\":\"_blank\",\"btnTocIfMobile\":\"true\",\"btnThumbsIfMobile\":\"true\",\"btnShareIfMobile\":\"false\",\"btnDownloadPagesIfMobile\":\"false\",\"btnDownloadPdfIfMobile\":\"true\",\"btnSoundIfMobile\":\"false\",\"btnExpandIfMobile\":\"true\",\"btnPrintIfMobile\":\"false\",\"lightboxCloseOnClick\":\"false\",\"btnSelect\":{\"enabled\":\"true\",\"title\":\"Select tool\",\"vAlign\":\"top\",\"hAlign\":\"right\"},\"sideBtnColor\":\"#fff\",\"sideBtnColorHover\":\"#fff\",\"sideBtnBackground\":\"rgba(0,0,0,.3)\",\"sideBtnRadius\":\"0\",\"sideBtnMargin\":\"0\",\"sideBtnSize\":\"40\",\"sideBtnPaddingV\":\"5\",\"sideBtnPaddingH\":\"5\",\"sideMenuOverBook\":\"true\",\"sideMenuOverMenu\":\"false\",\"sideMenuOverMenu2\":\"false\",\"rewriteSlug\":\"Disabled\",\"s\":\"12345678\"}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>In issue 04\/2021 of MD Magazine read:<\/p>\n<ul>\n<li>&#8211;<strong> GOLDEN PAGES: Florence Knoll<\/strong><\/li>\n<li>&#8211;<strong> Thomas Benzen <\/strong>&#8211; Danish simplicity and rationality <\/li>\n<li>&#8211; <strong>The story of Eero Saarinen\u2019s \u2018tulips\u2019 <\/strong><\/li>\n<li>&#8211; <strong>Dubai Expo 2020<\/strong><\/li>\n<\/ul>\n","protected":false},"author":2,"featured_media":15008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[63],"tags":[],"class_list":["post-15013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2021-2"],"_links":{"self":[{"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/posts\/15013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/comments?post=15013"}],"version-history":[{"count":1,"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/posts\/15013\/revisions"}],"predecessor-version":[{"id":23766,"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/posts\/15013\/revisions\/23766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/media\/15008"}],"wp:attachment":[{"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/media?parent=15013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/categories?post=15013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/md-magazine.info\/en\/wp-json\/wp\/v2\/tags?post=15013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}